{"id":3121,"date":"2022-10-27T11:00:45","date_gmt":"2022-10-27T02:00:45","guid":{"rendered":"https:\/\/oliverbayerlein.com\/?page_id=3121"},"modified":"2025-05-26T21:05:58","modified_gmt":"2025-05-26T12:05:58","slug":"campus-deutsch-hoeren-und-mitschreiben","status":"publish","type":"page","link":"https:\/\/oliverbayerlein.com\/de_de\/campus-deutsch-hoeren-und-mitschreiben\/","title":{"rendered":"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben"},"content":{"rendered":"<style>.kb-row-layout-id3121_4ce756-04 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3121_4ce756-04 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3121_4ce756-04 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3121_4ce756-04 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3121_4ce756-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3121_4ce756-04 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3121_4ce756-04 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3121_964bee-d1 > .kt-inside-inner-col,.kadence-column3121_964bee-d1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_964bee-d1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_964bee-d1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_964bee-d1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_964bee-d1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_964bee-d1{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_964bee-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_964bee-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_964bee-d1 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd, .wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd[data-kb-block=\"kb-adv-heading3121_d25b91-dd\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd[data-kb-block=\"kb-adv-heading3121_d25b91-dd\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_d25b91-dd[data-kb-block=\"kb-adv-heading3121_d25b91-dd\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading3121_d25b91-dd wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3121_d25b91-dd\">Die Reihe <em>Campus Deutsch<\/em> <\/h1>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a, .wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a[data-kb-block=\"kb-adv-heading3121_2a47a8-0a\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a[data-kb-block=\"kb-adv-heading3121_2a47a8-0a\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_2a47a8-0a[data-kb-block=\"kb-adv-heading3121_2a47a8-0a\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3121_2a47a8-0a wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3121_2a47a8-0a\">besteht aus den B\u00e4nden <em>H\u00f6ren und Mitschreiben<\/em>, <em>Lesen<\/em>, <em>Schreiben<\/em> und <em>Pr\u00e4sentieren und Diskutieren<\/em>. Sie ist f\u00fcr Studierende am \u00dcbergang der Sprachausbildung zum Fachstudium an einer deutschsprachigen Universit\u00e4t konzipiert. Das Kursmaterial hilft Lernenden, den Beginn ihres Fachstudiums sprachlich und methodisch zu bew\u00e4ltigen.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5, .wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"] a, .kt-adv-heading-link3121_5ce172-a5, .kt-adv-heading-link3121_5ce172-a5 .kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"]{color:var(--global-palette1, #3182CE);}.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"] a:hover, .kt-adv-heading-link3121_5ce172-a5:hover, .kt-adv-heading-link3121_5ce172-a5:hover .kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"]{color:var(--global-palette2, #2B6CB0);}.wp-block-kadence-advancedheading.kt-adv-heading3121_5ce172-a5[data-kb-block=\"kb-adv-heading3121_5ce172-a5\"] a, a.kb-advanced-heading-link.kt-adv-heading-link3121_5ce172-a5{text-decoration:none;}<\/style>\n<p class=\"kt-adv-heading3121_5ce172-a5 wp-block-kadence-advancedheading hls-none\" data-kb-block=\"kb-adv-heading3121_5ce172-a5\">Mit der&nbsp;<a href=\"https:\/\/www.hueber.de\/campus-deutsch\/app\">eigenen App zu Campus Deutsch<\/a>&nbsp;k\u00f6nnen Lehrende und Lernende unkompliziert und schnell auf die Audios und Videos sowie auf die zus\u00e4tzlichen Word-Dokumente und PDFs von&nbsp;<em>Campus Deutsch<\/em> zugreifen.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3121_c42f6f-d1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3121_c42f6f-d1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3121_c42f6f-d1 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1280px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:40px;padding-right:40px;padding-bottom:40px;padding-left:40px;grid-template-columns:minmax(0, calc(70% - ((80px * 1 )\/2)))minmax(0, calc(30% - ((80px * 1 )\/2)));}.kb-row-layout-id3121_c42f6f-d1 > .kt-row-layout-overlay{opacity:1;background-color:var(--global-palette7, #EDF2F7);}.kb-row-layout-id3121_c42f6f-d1 ,.kb-row-layout-id3121_c42f6f-d1 h1,.kb-row-layout-id3121_c42f6f-d1 h2,.kb-row-layout-id3121_c42f6f-d1 h3,.kb-row-layout-id3121_c42f6f-d1 h4,.kb-row-layout-id3121_c42f6f-d1 h5,.kb-row-layout-id3121_c42f6f-d1 h6{color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px){.kb-row-layout-id3121_c42f6f-d1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 2fr) minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3121_c42f6f-d1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3121_c42f6f-d1 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-left-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3121_473649-f0 > .kt-inside-inner-col,.kadence-column3121_473649-f0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_473649-f0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_473649-f0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_473649-f0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_473649-f0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_473649-f0{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_473649-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_473649-f0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_473649-f0 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9, .wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9[data-kb-block=\"kb-adv-heading3121_d0a31c-d9\"]{font-weight:400;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9[data-kb-block=\"kb-adv-heading3121_d0a31c-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_d0a31c-d9[data-kb-block=\"kb-adv-heading3121_d0a31c-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3121_d0a31c-d9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3121_d0a31c-d9\"><span style=\"color:#1A202C\" class=\"tadv-color\"><em>Campus Deutsch \u2013 H\u00f6ren und Mitschreiben<\/em><\/span><\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84, .wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84[data-kb-block=\"kb-adv-heading3121_f9e469-84\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84[data-kb-block=\"kb-adv-heading3121_f9e469-84\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_f9e469-84[data-kb-block=\"kb-adv-heading3121_f9e469-84\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3121_f9e469-84 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3121_f9e469-84\">Der Band enth\u00e4lt f\u00fcnf authentische Vortr\u00e4ge. Sie sind der Reihe&nbsp;<em>Aula<\/em>&nbsp;des SWR (jetzt Teil der Podcastreihe&nbsp;<em>SWR2 Wissen<\/em>) entnommen und behandeln aktuelle Themen aus verschiedenen Fachgebieten.<\/p>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79, .wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79[data-kb-block=\"kb-adv-heading3121_c45132-79\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79[data-kb-block=\"kb-adv-heading3121_c45132-79\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_c45132-79[data-kb-block=\"kb-adv-heading3121_c45132-79\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3121_c45132-79 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3121_c45132-79\">Die Studierende lernen Techniken, die sie in die Lage versetzen, eigenst\u00e4ndig wissenschaftlichen Vortr\u00e4gen oder Vorlesungen verstehend zu folgen und so mitzuschreiben, dass diese Vortr\u00e4ge anhand der Mitschriften rekapituliert werden k\u00f6nnen. Im Gundlagenkapitel werden Techniken des aktiven und vorausdenkenden H\u00f6rens sowie wesentliche Mitschreibtechniken vermittelt. In den darauf folgenden Kapiteln werden diese Techniken erweitert und vertieft. Die Inhalte der Vortr\u00e4ge behandeln<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items3121_300c3e-fa:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3121_300c3e-fa ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3121_300c3e-fa ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items3121_300c3e-fa ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items3121_300c3e-fa ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap, .kt-svg-icon-list-items3121_300c3e-fa ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap a{color:#021f40;color:#021f40;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items3121_300c3e-fa kt-svg-icon-list-columns-1 alignnone kt-list-icon-aligntop\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-3121_ead81d-23 .kt-svg-icon-list-single{font-size:20px !important;color:var(--global-palette2, #2B6CB0) !important;}.kt-svg-icon-list-item-3121_ead81d-23 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3121_ead81d-23 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Sprache und Gesellschaft<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3121_dd852b-c9 .kt-svg-icon-list-single{font-size:20px !important;color:var(--global-palette2, #2B6CB0) !important;}.kt-svg-icon-list-item-3121_dd852b-c9 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3121_dd852b-c9 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Der Ursprung der Gewalt<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3121_a6511e-c7 .kt-svg-icon-list-single{font-size:20px !important;color:var(--global-palette2, #2B6CB0) !important;}.kt-svg-icon-list-item-3121_a6511e-c7 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3121_a6511e-c7 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Arm und Reich in Deutschland<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3121_d1760f-e5 .kt-svg-icon-list-single{font-size:20px !important;color:var(--global-palette2, #2B6CB0) !important;}.kt-svg-icon-list-item-3121_d1760f-e5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3121_d1760f-e5 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Das Ged\u00e4chtnis der Gene<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-3121_9fd9bd-90 .kt-svg-icon-list-single{font-size:20px !important;color:var(--global-palette2, #2B6CB0) !important;}.kt-svg-icon-list-item-3121_9fd9bd-90 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-3121_9fd9bd-90 kt-svg-icon-list-style-default\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_chevronRight kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"9 18 15 12 9 6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Entschleunigung der Stadt<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75, .wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75[data-kb-block=\"kb-adv-heading3121_fb70b3-75\"]{font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75[data-kb-block=\"kb-adv-heading3121_fb70b3-75\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3121_fb70b3-75[data-kb-block=\"kb-adv-heading3121_fb70b3-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading3121_fb70b3-75 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3121_fb70b3-75\">Die Module nach dem Grundlagenkapitel sind in sich abgeschlossen. Sie k\u00f6nnen in beliebiger Reihenfolge verwendet werden. <\/p>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns_b2635a-5d{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btns_b2635a-5d .kt-button{font-weight:bold;font-style:normal;}.kt-btns_b2635a-5d .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns_b2635a-5d .kt-btn-wrap-0 .kt-button::before{display:none;}.kt-btns_b2635a-5d .kt-btn-wrap-1{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns_b2635a-5d .kt-btn-wrap-1 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns_b2635a-5d .kt-btn-wrap-1 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns_b2635a-5d .kt-btn-wrap-1 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kt-btn-align-left kt-btn-tablet-align-inherit kt-btn-mobile-align-inherit kt-btns-wrap kt-btns_b2635a-5d\"><div class=\"kt-btn-wrap kt-btn-wrap-0\"><a class=\"kt-button button kt-btn-0-action kt-btn-size-small kt-btn-style-basic kt-btn-svg-show-always kt-btn-has-text-true kt-btn-has-svg-true kb-btn-global-inherit wp-block-button__link\" href=\"https:\/\/www.hueber.de\/campus-deutsch\/musterseiten\" target=\"_blank\" rel=\"noreferrer noopener\"><span class=\"kt-btn-inner-text\">Probeseiten<\/span><div style=\"display:inline-flex;justify-content:center;align-items:center\" class=\"kt-btn-svg-icon kt-btn-svg-icon-fe_externalLink kt-btn-side-right\"><svg style=\"display:inline-block;vertical-align:middle\" viewBox=\"0 0 24 24\" height=\"1em\" width=\"1em\" fill=\"none\" stroke=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"><\/path><polyline points=\"15 3 21 3 21 9\"><\/polyline><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"><\/line><\/svg><\/div><\/a><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col,.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_b5e2a0-e4{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_b5e2a0-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_b5e2a0-e4 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image3121_5431ab-2c .kb-image-has-overlay:after{opacity:0.3;}.kb-image3121_5431ab-2c img.kb-img, .kb-image3121_5431ab-2c .kb-img img{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;filter:drop-shadow(0px 0px 14px rgba(0, 0, 0, 0.2));}@media all and (max-width: 1024px){.kb-image3121_5431ab-2c img.kb-img, .kb-image3121_5431ab-2c .kb-img img{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}@media all and (max-width: 767px){.kb-image3121_5431ab-2c img.kb-img, .kb-image3121_5431ab-2c .kb-img img{border-top-color:var(--global-palette2, #2B6CB0);border-top-style:solid;border-right-color:var(--global-palette2, #2B6CB0);border-right-style:solid;border-bottom-color:var(--global-palette2, #2B6CB0);border-bottom-style:solid;border-left-color:var(--global-palette2, #2B6CB0);border-left-style:solid;}}<\/style>\n<figure class=\"wp-block-kadence-image kb-image3121_5431ab-2c size-full\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg\" alt=\"Campus Deutsch H\u00f6ren und Mitschreiben\" class=\"kb-img wp-image-2091\" srcset=\"\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg 768w, \/wp-content\/uploads\/2020\/11\/9783191510039-2-225x300.jpg 225w, \/wp-content\/uploads\/2020\/11\/9783191510039-2-676x901.jpg 676w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3121_7e9209-fc{margin-top:40px;margin-bottom:40px;}.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1280px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:0px;padding-bottom:0px;}.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id3121_7e9209-fc > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3121_7e9209-fc > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3121_7e9209-fc alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3121_6c8f53-cb > .kt-inside-inner-col,.kadence-column3121_6c8f53-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_6c8f53-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_6c8f53-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_6c8f53-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_6c8f53-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_6c8f53-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_6c8f53-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_6c8f53-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_6c8f53-cb inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px;margin-top:50px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette2, #2B6CB0);}.kt-info-box3121_2a8062-ed.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3121_2a8062-ed .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box3121_2a8062-ed .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.3333%;width:768px;height:0px;max-width:100%;}.kt-info-box3121_2a8062-ed .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3121_2a8062-ed .kt-info-svg-icon-flip, .kt-info-box3121_2a8062-ed .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:#ffffff;border-color:#eeeeee;border-top-width:5px;border-right-width:5px;border-bottom-width:5px;border-left-width:5px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-media-container{margin-top:-75px;margin-right:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:#ffffff;border-color:#eeeeee;}.kt-info-box3121_2a8062-ed .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3121_2a8062-ed .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette4, #2D3748);}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}@media all and (max-width: 767px){.kt-info-box3121_2a8062-ed .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3121_2a8062-ed\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\" href=\"https:\/\/oliverbayerlein.com\/campus-deutsch-lesen\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783190510030-3.jpg\" alt=\"\" width=\"768\" height=\"1024\" class=\"kt-info-box-image wp-image-2088\" srcset=\"\/wp-content\/uploads\/2020\/11\/9783190510030-3.jpg 768w, \/wp-content\/uploads\/2020\/11\/9783190510030-3-225x300.jpg 225w, \/wp-content\/uploads\/2020\/11\/9783190510030-3-676x901.jpg 676w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Campus Deutsch<\/h3><p class=\"kt-blocks-info-box-text\">Lesen <\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3121_846000-36 > .kt-inside-inner-col,.kadence-column3121_846000-36 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_846000-36 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_846000-36 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_846000-36 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_846000-36 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_846000-36{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_846000-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_846000-36 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_846000-36 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px;margin-top:50px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette2, #2B6CB0);}.kt-info-box3121_62b767-d4.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3121_62b767-d4 .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box3121_62b767-d4 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.3333%;width:768px;height:0px;max-width:100%;}.kt-info-box3121_62b767-d4 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3121_62b767-d4 .kt-info-svg-icon-flip, .kt-info-box3121_62b767-d4 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:#ffffff;border-color:#eeeeee;border-top-width:5px;border-right-width:5px;border-bottom-width:5px;border-left-width:5px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-media-container{margin-top:-75px;margin-right:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:#ffffff;border-color:#eeeeee;}.kt-info-box3121_62b767-d4 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3121_62b767-d4 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}@media all and (max-width: 767px){.kt-info-box3121_62b767-d4 .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3121_62b767-d4\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\" href=\"https:\/\/oliverbayerlein.com\/campus-deutsch-praesentieren-und-diskutieren\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783192010033-5.jpg\" alt=\"Campus Deutsch - Pr\u00e4sentieren und Diskutieren\" width=\"768\" height=\"1024\" class=\"kt-info-box-image wp-image-2090\" srcset=\"\/wp-content\/uploads\/2020\/11\/9783192010033-5.jpg 768w, \/wp-content\/uploads\/2020\/11\/9783192010033-5-225x300.jpg 225w, \/wp-content\/uploads\/2020\/11\/9783192010033-5-676x901.jpg 676w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><meta charset=\"utf-8\">Campus Deutsch<\/h3><p class=\"kt-blocks-info-box-text\">Pr\u00e4sentieren und Diskutieren<\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3121_602456-03 > .kt-inside-inner-col,.kadence-column3121_602456-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3121_602456-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3121_602456-03 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3121_602456-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3121_602456-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3121_602456-03{position:relative;}@media all and (max-width: 1024px){.kadence-column3121_602456-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3121_602456-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3121_602456-03 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:var(--global-palette7, #EDF2F7);padding-top:24px;padding-right:24px;padding-bottom:24px;padding-left:24px;margin-top:50px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap:hover{background:var(--global-palette2, #2B6CB0);}.kt-info-box3121_ac92a9-4e.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3121_ac92a9-4e .kadence-info-box-image-inner-intrisic-container{max-width:100px;}.kt-info-box3121_ac92a9-4e .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:133.3333%;width:768px;height:0px;max-width:100%;}.kt-info-box3121_ac92a9-4e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3121_ac92a9-4e .kt-info-svg-icon-flip, .kt-info-box3121_ac92a9-4e .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:#ffffff;border-color:#eeeeee;border-top-width:5px;border-right-width:5px;border-bottom-width:5px;border-left-width:5px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-media-container{margin-top:-75px;margin-right:0px;margin-bottom:20px;margin-left:0px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette7, #EDF2F7);background:#ffffff;border-color:#eeeeee;}.kt-info-box3121_ac92a9-4e .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-weight:600;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap:hover h3.kt-blocks-info-box-title{color:var(--global-palette9, #ffffff);}.kt-info-box3121_ac92a9-4e .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-text{color:var(--global-palette9, #ffffff);}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}@media all and (max-width: 767px){.kt-info-box3121_ac92a9-4e .kt-blocks-info-box-link-wrap{border-top:5px solid var(--global-palette9, #ffffff);border-right:5px solid var(--global-palette9, #ffffff);border-bottom:5px solid var(--global-palette9, #ffffff);border-left:5px solid var(--global-palette9, #ffffff);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3121_ac92a9-4e\"><a class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-left\" href=\"https:\/\/oliverbayerlein.com\/campus-deutsch-schreiben\/\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic\"><img decoding=\"async\" src=\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191010034-3.jpg\" alt=\"\" width=\"768\" height=\"1024\" class=\"kt-info-box-image wp-image-2089\" srcset=\"\/wp-content\/uploads\/2020\/11\/9783191010034-3.jpg 768w, \/wp-content\/uploads\/2020\/11\/9783191010034-3-225x300.jpg 225w, \/wp-content\/uploads\/2020\/11\/9783191010034-3-676x901.jpg 676w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><meta charset=\"utf-8\">Campus Deutsch<\/h3><p class=\"kt-blocks-info-box-text\">Schreiben<\/p><\/div><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3268_8d2715-ba{margin-top:25px;margin-bottom:25px;}.kb-row-layout-id3268_8d2715-ba > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3268_8d2715-ba > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3268_8d2715-ba > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:15px;padding-bottom:15px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3268_8d2715-ba > .kt-row-layout-overlay{opacity:1;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-top-sep{height:50px;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-top-sep svg{width:100%;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-top-sep svg{fill:#e8cd21!important;}@media all and (max-width: 1024px){.kb-row-layout-id3268_8d2715-ba > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id3268_8d2715-ba > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id3268_8d2715-ba .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3268_8d2715-ba alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle\">\n<style>.kadence-column3268_75738a-27 > .kt-inside-inner-col{display:flex;}.kadence-column3268_75738a-27 > .kt-inside-inner-col,.kadence-column3268_75738a-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3268_75738a-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3268_75738a-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3268_75738a-27{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3268_75738a-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3268_75738a-27{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3268_75738a-27{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3268_75738a-27{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3268_75738a-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3268_75738a-27 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedbtn.kt-btns3268_351bcc-90, .site .entry-content .wp-block-kadence-advancedbtn.kt-btns3268_351bcc-90, .wp-block-kadence-advancedbtn.kb-btns3268_351bcc-90, .site .entry-content .wp-block-kadence-advancedbtn.kb-btns3268_351bcc-90{margin-top:40px;}.wp-block-kadence-advancedbtn.kb-btns3268_351bcc-90{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns3268_351bcc-90 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns3268_351bcc-90\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn3268_822819-0c.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn3268_822819-0c.kb-button{font-weight:bold;}<\/style><a class=\"kb-button kt-button button kb-btn3268_822819-0c kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\" href=\"https:\/\/oliverbayerlein.com\/publikationen\/\"><span class=\"kt-btn-inner-text\">Weitere Publikationen von Oliver Bayerlein<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3721_9cf57e-84 .kt-block-spacer{height:75px;}.wp-block-kadence-spacer.kt-block-spacer-3721_9cf57e-84 .kt-divider{border-top-width:3px;height:1px;border-top-color:var(--global-palette2, #2B6CB0);width:80%;border-top-style:dotted;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3721_9cf57e-84\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5, .wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5[data-kb-block=\"kb-adv-heading4383_0dbc30-d5\"]{text-align:center;font-style:normal;font-family:apparat-light;}.wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5[data-kb-block=\"kb-adv-heading4383_0dbc30-d5\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5[data-kb-block=\"kb-adv-heading4383_0dbc30-d5\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5, .wp-block-kadence-advancedheading.kt-adv-heading4383_0dbc30-d5[data-kb-block=\"kb-adv-heading4383_0dbc30-d5\"]{font-size:20px;}}<\/style>\n<h3 class=\"kt-adv-heading4383_0dbc30-d5 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4383_0dbc30-d5\">Sie m\u00f6chten selbstst\u00e4ndig mehr Deutsch \u00fcben? <\/h3>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6, .wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6[data-kb-block=\"kb-adv-heading4383_3d8370-b6\"]{text-align:center;font-style:normal;font-family:apparat-light;}.wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6[data-kb-block=\"kb-adv-heading4383_3d8370-b6\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6[data-kb-block=\"kb-adv-heading4383_3d8370-b6\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6, .wp-block-kadence-advancedheading.kt-adv-heading4383_3d8370-b6[data-kb-block=\"kb-adv-heading4383_3d8370-b6\"]{font-size:20px;}}<\/style>\n<h4 class=\"kt-adv-heading4383_3d8370-b6 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4383_3d8370-b6\">Klicken Sie auf einen der Buttons, um zu Aufgaben f\u00fcr das gew\u00e4hlte Niveau zu wechseln.<\/h4>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btns4383_9a01a3-33{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns4383_9a01a3-33 .kt-button{font-weight:normal;font-style:normal;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns4383_9a01a3-33\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4383_6460d2-5e.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4383_6460d2-5e.kb-button{font-weight:bold;}<\/style><a class=\"kb-button kt-button button kb-btn4383_6460d2-5e kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\" href=\"https:\/\/oliverbayerlein.com\/deutsch-lernen-mit-videos-niveau-a\/\"><span class=\"kt-btn-inner-text\">Niveau A<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4383_601a95-48.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4383_601a95-48.kb-button{font-weight:bold;}<\/style><a class=\"kb-button kt-button button kb-btn4383_601a95-48 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\" href=\"https:\/\/oliverbayerlein.com\/deutsch-wiederholen-mit-interaktiven-aufgaben-niveau-b\/\"><span class=\"kt-btn-inner-text\">Niveau B<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn4383_e82924-1f.kb-button{width:initial;}.wp-block-kadence-advancedbtn .kb-btn4383_e82924-1f.kb-button{font-weight:bold;}<\/style><a class=\"kb-button kt-button button kb-btn4383_e82924-1f kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-kadence-singlebtn\" href=\"https:\/\/oliverbayerlein.com\/deutsch-lernen-mit-interaktiven-videos\/\"><span class=\"kt-btn-inner-text\">Niveau C<\/span><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRight kt-btn-icon-side-right\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><line x1=\"5\" y1=\"12\" x2=\"19\" y2=\"12\"\/><polyline points=\"12 5 19 12 12 19\"\/><\/svg><\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Reihe Campus Deutsch besteht aus den B\u00e4nden H\u00f6ren und Mitschreiben, Lesen, Schreiben und Pr\u00e4sentieren und Diskutieren. Sie ist f\u00fcr Studierende am \u00dcbergang der Sprachausbildung zum Fachstudium an einer deutschsprachigen Universit\u00e4t konzipiert. Das Kursmaterial hilft Lernenden, den Beginn ihres Fachstudiums sprachlich und methodisch zu bew\u00e4ltigen. Mit der&nbsp;eigenen App zu Campus Deutsch&nbsp;k\u00f6nnen Lehrende und Lernende unkompliziert&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-3121","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein<\/title>\n<meta name=\"description\" content=\"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oliverbayerlein.com\/de_de\/campus-deutsch-hoeren-und-mitschreiben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein\" \/>\n<meta property=\"og:description\" content=\"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oliverbayerlein.com\/de_de\/campus-deutsch-hoeren-und-mitschreiben\/\" \/>\n<meta property=\"og:site_name\" content=\"Dr. Oliver Bayerlein\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-26T12:05:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/\",\"url\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/\",\"name\":\"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein\",\"isPartOf\":{\"@id\":\"https:\/\/oliverbayerlein.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg\",\"datePublished\":\"2022-10-27T02:00:45+00:00\",\"dateModified\":\"2025-05-26T12:05:58+00:00\",\"description\":\"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl\",\"breadcrumb\":{\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage\",\"url\":\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg\",\"contentUrl\":\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/oliverbayerlein.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oliverbayerlein.com\/#website\",\"url\":\"https:\/\/oliverbayerlein.com\/\",\"name\":\"Dr. Oliver Bayerlein\",\"description\":\"Lernen und Lehren mit Medien\",\"publisher\":{\"@id\":\"https:\/\/oliverbayerlein.com\/#\/schema\/person\/ce81d2e334fd5bff960e2b29e3db6c38\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oliverbayerlein.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/oliverbayerlein.com\/#\/schema\/person\/ce81d2e334fd5bff960e2b29e3db6c38\",\"name\":\"Oliver Bayerlein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/oliverbayerlein.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2015\/03\/Hanko-e1426126360983.jpg\",\"contentUrl\":\"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2015\/03\/Hanko-e1426126360983.jpg\",\"width\":120,\"height\":118,\"caption\":\"Oliver Bayerlein\"},\"logo\":{\"@id\":\"https:\/\/oliverbayerlein.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/oliverbayerlein.com\",\"https:\/\/www.instagram.com\/oliverbayerlein\/\",\"https:\/\/www.youtube.com\/@oliverbayerlein\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein","description":"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oliverbayerlein.com\/de_de\/campus-deutsch-hoeren-und-mitschreiben\/","og_locale":"de_DE","og_type":"article","og_title":"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein","og_description":"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl","og_url":"https:\/\/oliverbayerlein.com\/de_de\/campus-deutsch-hoeren-und-mitschreiben\/","og_site_name":"Dr. Oliver Bayerlein","article_modified_time":"2025-05-26T12:05:58+00:00","og_image":[{"width":768,"height":1024,"url":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/","url":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/","name":"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben Dr. Oliver Bayerlein","isPartOf":{"@id":"https:\/\/oliverbayerlein.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage"},"image":{"@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage"},"thumbnailUrl":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg","datePublished":"2022-10-27T02:00:45+00:00","dateModified":"2025-05-26T12:05:58+00:00","description":"Campus Deutsch H\u00f6ren und Mitschreiben: Vorlesungen und Vortr\u00e4ge erfolgreich mitschreiben. Autoren: O. Bayerlein , M. Raindl","breadcrumb":{"@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#primaryimage","url":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg","contentUrl":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2020\/11\/9783191510039-2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/oliverbayerlein.com\/campus-deutsch-hoeren-und-mitschreiben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/oliverbayerlein.com\/"},{"@type":"ListItem","position":2,"name":"Campus Deutsch \u2022 H\u00f6ren und Mitschreiben"}]},{"@type":"WebSite","@id":"https:\/\/oliverbayerlein.com\/#website","url":"https:\/\/oliverbayerlein.com\/","name":"Dr. Oliver Bayerlein","description":"Lernen und Lehren mit Medien","publisher":{"@id":"https:\/\/oliverbayerlein.com\/#\/schema\/person\/ce81d2e334fd5bff960e2b29e3db6c38"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oliverbayerlein.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/oliverbayerlein.com\/#\/schema\/person\/ce81d2e334fd5bff960e2b29e3db6c38","name":"Oliver Bayerlein","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/oliverbayerlein.com\/#\/schema\/person\/image\/","url":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2015\/03\/Hanko-e1426126360983.jpg","contentUrl":"https:\/\/oliverbayerlein.com\/wp-content\/uploads\/2015\/03\/Hanko-e1426126360983.jpg","width":120,"height":118,"caption":"Oliver Bayerlein"},"logo":{"@id":"https:\/\/oliverbayerlein.com\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/oliverbayerlein.com","https:\/\/www.instagram.com\/oliverbayerlein\/","https:\/\/www.youtube.com\/@oliverbayerlein"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"Oliver","author_link":"https:\/\/oliverbayerlein.com\/de_de\/author\/oliver-bayerlein\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/pages\/3121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":0,"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/pages\/3121\/revisions"}],"wp:attachment":[{"href":"https:\/\/oliverbayerlein.com\/de_de\/wp-json\/wp\/v2\/media?parent=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}